{"id":98,"count":2,"description":"","link":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/","name":"Rose Gold","slug":"rose-gold","taxonomy":"product_cat","parent":77,"meta":[],"menu_order":0,"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/98\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/#listItem\",\"name\":\"Gold\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/#listItem\",\"position\":3,\"name\":\"Gold\",\"item\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/rose-gold\\\/#listItem\",\"name\":\"Rose Gold\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/rose-gold\\\/#listItem\",\"position\":4,\"name\":\"Rose Gold\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/product-category\\\/gold\\\/#listItem\",\"name\":\"Gold\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/98\\\/#collectionpage\",\"url\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/98\\\/\",\"name\":\"Rose Gold - GK MILAN\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/98\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/#organization\",\"name\":\"GK MILAN\",\"url\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/#website\",\"url\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/\",\"name\":\"GK MILAN\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/gkmilan.com\\\/gkmilan\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Rose Gold - GK MILAN","description":"","canonical_url":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/98\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan#listItem","position":1,"name":"Home","item":"https:\/\/gkmilan.com\/gkmilan","nextItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/gkmilan.com\/gkmilan\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/#listItem","name":"Gold"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/#listItem","position":3,"name":"Gold","item":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/#listItem","name":"Rose Gold"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/#listItem","position":4,"name":"Rose Gold","previousItem":{"@type":"ListItem","@id":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/#listItem","name":"Gold"}}]},{"@type":"CollectionPage","@id":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/98\/#collectionpage","url":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/98\/","name":"Rose Gold - GK MILAN","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/gkmilan.com\/gkmilan\/#website"},"breadcrumb":{"@id":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/98\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/gkmilan.com\/gkmilan\/#organization","name":"GK MILAN","url":"https:\/\/gkmilan.com\/gkmilan\/"},{"@type":"WebSite","@id":"https:\/\/gkmilan.com\/gkmilan\/#website","url":"https:\/\/gkmilan.com\/gkmilan\/","name":"GK MILAN","inLanguage":"en-US","publisher":{"@id":"https:\/\/gkmilan.com\/gkmilan\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gkmilan.com\/gkmilan\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gkmilan.com\/gkmilan\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/\" title=\"Gold\">Gold<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRose Gold\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gkmilan.com\/gkmilan"},{"label":"Shop","link":"https:\/\/gkmilan.com\/gkmilan\/shop\/"},{"label":"Gold","link":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/"},{"label":"Rose Gold","link":"https:\/\/gkmilan.com\/gkmilan\/product-category\/gold\/rose-gold\/"}],"_links":{"self":[{"href":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product_cat\/77"}],"wp:post_type":[{"href":"https:\/\/gkmilan.com\/gkmilan\/wp-json\/wp\/v2\/product?product_cat=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}